{"id":3798,"date":"2016-03-31T15:20:33","date_gmt":"2016-03-31T19:20:33","guid":{"rendered":"http:\/\/www.hireimmigrantsottawa.ca\/?post_type=2016-ecc-post&#038;p=3798"},"modified":"2016-04-01T10:19:23","modified_gmt":"2016-04-01T14:19:23","slug":"annahid","status":"publish","type":"2016-ecc-post","link":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/","title":{"rendered":"Faits saillants de l\u2019atelier &#8211; Annahid Dashtgard"},"content":{"rendered":"<figure id=\"attachment_3820\" aria-describedby=\"caption-attachment-3820\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-3820\" src=\"http:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/Annahid-Audience-1024x511.jpg\" alt=\"Annahid-Audience\" width=\"510\" height=\"254\" srcset=\"https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/Annahid-Audience.jpg 1024w, https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/Annahid-Audience-300x150.jpg 300w, https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/Annahid-Audience-768x383.jpg 768w\" sizes=\"(max-width: 510px) 100vw, 510px\" \/><figcaption id=\"caption-attachment-3820\" class=\"wp-caption-text\">Annahid Dashtgard, Associ\u00e9e principale, Anima Leadership Inc.,<\/figcaption><\/figure>\n<p>\u00ab Diversit\u00e9 profonde : D\u00e9couvrir les pr\u00e9jug\u00e9s et les \u2018angles morts\u2019. \u00bb Messages cl\u00e9s d\u2019<a href=\"http:\/\/animaleadership.com\/about\/team\/annahid-dashtgard\/\" target=\"_blank\">Annahid Dashtgard<\/a>, associ\u00e9e principale chez Anima Leadership Inc., une entreprise d\u2019experts-conseils prim\u00e9e qui offre des solutions innovatrices de formation et de changement organisationnel en vue de favoriser des milieux de travail productifs et inclusifs.<\/p>\n<p>La soci\u00e9t\u00e9 est de plus en plus ouverte \u00e0 discuter de la diversit\u00e9 et de l\u2019inclusion. La controverse r\u00e9cente concernant la repr\u00e9sentation aux Academy Awards (<a href=\"https:\/\/twitter.com\/oscarssowhite\">#oscarssowhite<\/a>) marque un moment culturel important.<\/p>\n<p>Les moments culturels sont l\u2019occasion de r\u00e9orienter la conversation publique au-del\u00e0 d\u2019une discussion sur les raisons pour lesquelles la diversit\u00e9 et l\u2019inclusion sont importantes et de se concentrer plut\u00f4t sur la fa\u00e7on dont la soci\u00e9t\u00e9 peut envisager davantage de diversit\u00e9 et d\u2019\u00e9quit\u00e9.<\/p>\n<p>Un aspect de la cr\u00e9ation de milieux de travail inclusifs est la sensibilisation aux \u00ab angles morts \u00bb : ce que nous ne voyons pas a souvent plus de pouvoir de nous contr\u00f4ler et d\u2019orienter notre comportement.<\/p>\n<p>Les \u00e9tudes de la neuroscience indiquent que l\u2019on peut croire que nous traitons chacun de la m\u00eame fa\u00e7on, mais autre chose se passe dans notre esprit inconscient, qui est domin\u00e9 par les \u00e9motions et l\u2019instinct.<\/p>\n<p>Notre esprit inconscient est programm\u00e9 pour manifester de l\u2019empathie envers ceux qui nous ressemblent le plus.<\/p>\n<p>L\u2019anxi\u00e9t\u00e9, la peur et la vigilance, surtout en ce qui a trait \u00e0 la race et \u00e0 la couleur de la peau, sont activ\u00e9es dans l\u2019amygdale du cerveau, qui traite les r\u00e9actions \u00e9motionnelles d\u00e8s l\u2019\u00e2ge de trois ans.<\/p>\n<p>\u00c9tant donn\u00e9 ces \u00ab angles morts \u00bb, les leaders doivent \u00eatre conscients de ce qu\u2019ils signalent involontairement. Leur comportement verbal et non verbal, qu\u2019il soit intentionnel ou non, exerce une force puissante sur le ton \u00e9motionnel d\u2019un groupe.<\/p>\n<p>Annahid a racont\u00e9 sa propre exp\u00e9rience en tant qu\u2019immigrante, de son r\u00e9installation de l\u2019Iran jusqu\u2019en Angleterre alors qu\u2019elle \u00e9tait enfant et, enfin, jusqu\u2019en Alberta. \u00c0 l\u2019\u00e9cole, elle avait l\u2019air diff\u00e9rent et \u00e9tait la victime d\u2019intimidation. Les sentiments qui en d\u00e9coulaient \u2013 la peur, la col\u00e8re, la tristesse et la honte \u2013 l\u2019ont amen\u00e9e \u00e0 d\u00e9velopper un trouble de l\u2019alimentation.<\/p>\n<p>Annahid a partag\u00e9 son histoire personnelle pour illustrer la fa\u00e7on dont les diff\u00e9rentes personnes traitent les \u00e9motions et r\u00e9agissent \u00e0 l\u2019exclusion.<\/p>\n<p>Les participants ont \u00e9t\u00e9 invit\u00e9s \u00e0 prendre part \u00e0 un exercice d\u2019association libre. En petits groupes, ils ont \u00e9num\u00e9r\u00e9 les premiers mots qui leur venaient \u00e0 l\u2019esprit pour les termes suivants : tiers monde, Iran, immigrant.<\/p>\n<p>En cernant les st\u00e9r\u00e9otypes et les images associ\u00e9s \u00e0 ces mots, Annahid a fait remarquer qu\u2019ils sont plus n\u00e9gatifs que positifs. Ces histoires culturelles constituent les normes en ce qui concerne notre perception de gens de diff\u00e9rentes cultures.<\/p>\n<p>Ils repr\u00e9sentent \u00e9galement les pens\u00e9es qui refl\u00e8tent les pr\u00e9jug\u00e9s cach\u00e9s programm\u00e9s dans notre cerveau. Dans leur ensemble, ils sont refl\u00e9t\u00e9s dans les politiques et les proc\u00e9dures des organisations.<\/p>\n<p>Les \u00e9tudes montrent que la fa\u00e7on la plus efficace de lutter contre ces st\u00e9r\u00e9otypes n\u00e9gatifs est de d\u00e9velopper consciemment des contre-st\u00e9r\u00e9otypes positifs.<\/p>\n<p><img decoding=\"async\" class=\"alignleft wp-image-3797\" src=\"http:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/IMG_0931-300x200.jpg\" alt=\"Summit Learning Exchange-Annahid\" width=\"291\" height=\"194\" srcset=\"https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/IMG_0931-300x200.jpg 300w, https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/IMG_0931-768x512.jpg 768w, https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/IMG_0931.jpg 1024w\" sizes=\"(max-width: 291px) 100vw, 291px\" \/>Les participants ont ensuite \u00e9t\u00e9 invit\u00e9s \u00e0 partager leurs exp\u00e9riences personnelles d\u2019exclusion. Les histoires ont sugg\u00e9r\u00e9 que l\u2019intimidation pendant l\u2019enfance \u00e9tait une exp\u00e9rience commune de tous ceux qui se sentaient exclus. En outre, le traumatisme et les blessures \u00e0 l\u2019issue de l\u2019exclusion peuvent durer toute la vie.<\/p>\n<p>Les participants ont parl\u00e9 de d\u00e9montrer plus d\u2019empathie envers les nouveaux arrivants lorsqu\u2019ils ont r\u00e9fl\u00e9chi \u00e0 leurs propres exp\u00e9riences d\u2019exclusion sous toutes ses formes.<\/p>\n<p>Annahid a fait mention d\u2019\u00e9tudes qui indiquent que des niveaux \u00e9lev\u00e9s de pr\u00e9jug\u00e9s implicites se traduisent par :<br \/>\n\u2022 des employeurs qui sont moins susceptibles de passer en entrevue ou d\u2019embaucher des candidats qui ont des noms arabes ou musulmans;<br \/>\n\u2022 des m\u00e9decins qui sont moins susceptibles de prescrire des anticoagulants salvateurs aux patients noirs;<br \/>\n\u2022 des policiers qui sont plus susceptibles de brandir leur arme sur les personnes de couleur.<\/p>\n<p>Comment r\u00e9duire vos pr\u00e9jug\u00e9s personnels :<br \/>\n\u2022 Acceptez vos pr\u00e9jug\u00e9s et contestez vos intentions.<br \/>\n\u2022 Faites preuve de compassion envers les autres.<br \/>\n\u2022 Prenez-vous sur le fait, nommez le pr\u00e9jug\u00e9 et analysez-le.<br \/>\n\u2022 Remarquez vos sentiments et abordez consciemment le pr\u00e9jug\u00e9 : soyez diligent lorsque vous remarquez et abordez un pr\u00e9jug\u00e9.<\/p>\n<p>Strat\u00e9gies de r\u00e9duction des pr\u00e9jug\u00e9s dans votre organisation :<br \/>\n\u2022 Cernez les champions de la diversit\u00e9 parmi les cadres sup\u00e9rieurs.<br \/>\n\u2022 Int\u00e9grez la diversit\u00e9, l\u2019inclusion et l\u2019\u00e9quit\u00e9 dans les plans strat\u00e9giques.<br \/>\n\u2022 \u00c9laborez un programme robuste d\u2019int\u00e9gration des nouveaux employ\u00e9s.<br \/>\n\u2022 Renseignez tous les employ\u00e9s sur leurs droits, y compris les politiques et les pratiques relatives aux mesures d\u2019adaptation en milieu de travail, au harc\u00e8lement et \u00e0 la discrimination, et \u00e0 la r\u00e9solution de conflit officielle.<br \/>\n\u2022 Int\u00e9grez des m\u00e9thodes impartiales de recrutement, de fid\u00e9lisation et d\u2019avancement professionnel.<br \/>\n\u2022 Recueillez des donn\u00e9es et mesurez les progr\u00e8s du rendement en mati\u00e8re de diversit\u00e9 de votre organisation par rapport aux objectifs.<br \/>\n\u2022 Sensibilisez vos employ\u00e9s et leaders aux avantages de la diversit\u00e9 et \u00e0 la fa\u00e7on dont fonctionnent les pr\u00e9jug\u00e9s.<\/p>\n<p>Ces strat\u00e9gies s\u2019appliquent \u00e0 tous les types d\u2019exclusion : la race, le sexe, l\u2019orientation sexuelle, la religion, l\u2019\u00e2ge et la capacit\u00e9 physique.<\/p>\n<p><strong>Ouvrages recommand\u00e9s : <\/strong><a href=\"http:\/\/deepdiversity.animaleadership.com\">Deep Diversity: Overcoming Us vs Them<\/a> de <a href=\"http:\/\/deepdiversity.animaleadership.com\/about\/\">Shakil Choudhury <\/a>[en anglais seulement]<\/p>\n","protected":false},"featured_media":3797,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_links_to":"","_links_to_target":""},"categories":[],"tags":[],"class_list":["post-3798","2016-ecc-post","type-2016-ecc-post","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Faits saillants de l\u2019atelier - Annahid Dashtgard - Hire Immigrants Ottawa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Faits saillants de l\u2019atelier - Annahid Dashtgard - Hire Immigrants Ottawa\" \/>\n<meta property=\"og:description\" content=\"\u00ab Diversit\u00e9 profonde : D\u00e9couvrir les pr\u00e9jug\u00e9s et les \u2018angles morts\u2019. \u00bb Messages cl\u00e9s d\u2019Annahid Dashtgard, associ\u00e9e principale chez Anima Leadership Inc., une entreprise d\u2019experts-conseils prim\u00e9e qui offre des solutions innovatrices de formation et de changement organisationnel en vue de favoriser des milieux de travail productifs et inclusifs. La soci\u00e9t\u00e9 est de plus en plus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/\" \/>\n<meta property=\"og:site_name\" content=\"Hire Immigrants Ottawa\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-01T14:19:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/IMG_0931.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@HireImmOttawa\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/fr\\\/2016-ecc-post\\\/annahid\\\/\",\"url\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/fr\\\/2016-ecc-post\\\/annahid\\\/\",\"name\":\"Faits saillants de l\u2019atelier - Annahid Dashtgard - Hire Immigrants Ottawa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/fr\\\/2016-ecc-post\\\/annahid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/fr\\\/2016-ecc-post\\\/annahid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/IMG_0931.jpg\",\"datePublished\":\"2016-03-31T19:20:33+00:00\",\"dateModified\":\"2016-04-01T14:19:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/fr\\\/2016-ecc-post\\\/annahid\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/fr\\\/2016-ecc-post\\\/annahid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/fr\\\/2016-ecc-post\\\/annahid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/IMG_0931.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/IMG_0931.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/fr\\\/2016-ecc-post\\\/annahid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faits saillants de l\u2019atelier &#8211; Annahid Dashtgard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/\",\"name\":\"Hire Immigrants Ottawa\",\"description\":\"increases the capacity of employers to attract and integrate skilled immigrants\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/#organization\",\"name\":\"Hire Immigrants Ottawa\",\"url\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/hio-logo_bow_EN_web.png\",\"contentUrl\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/hio-logo_bow_EN_web.png\",\"width\":745,\"height\":160,\"caption\":\"Hire Immigrants Ottawa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hireimmigrantsottawa.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/HireImmOttawa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/hireimmigrantsottawa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Faits saillants de l\u2019atelier - Annahid Dashtgard - Hire Immigrants Ottawa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/","og_locale":"fr_FR","og_type":"article","og_title":"Faits saillants de l\u2019atelier - Annahid Dashtgard - Hire Immigrants Ottawa","og_description":"\u00ab Diversit\u00e9 profonde : D\u00e9couvrir les pr\u00e9jug\u00e9s et les \u2018angles morts\u2019. \u00bb Messages cl\u00e9s d\u2019Annahid Dashtgard, associ\u00e9e principale chez Anima Leadership Inc., une entreprise d\u2019experts-conseils prim\u00e9e qui offre des solutions innovatrices de formation et de changement organisationnel en vue de favoriser des milieux de travail productifs et inclusifs. La soci\u00e9t\u00e9 est de plus en plus [&hellip;]","og_url":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/","og_site_name":"Hire Immigrants Ottawa","article_modified_time":"2016-04-01T14:19:23+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/IMG_0931.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@HireImmOttawa","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/","url":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/","name":"Faits saillants de l\u2019atelier - Annahid Dashtgard - Hire Immigrants Ottawa","isPartOf":{"@id":"https:\/\/www.hireimmigrantsottawa.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/#primaryimage"},"image":{"@id":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/IMG_0931.jpg","datePublished":"2016-03-31T19:20:33+00:00","dateModified":"2016-04-01T14:19:23+00:00","breadcrumb":{"@id":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/#primaryimage","url":"https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/IMG_0931.jpg","contentUrl":"https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2016\/03\/IMG_0931.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/2016-ecc-post\/annahid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hireimmigrantsottawa.ca\/"},{"@type":"ListItem","position":2,"name":"Faits saillants de l\u2019atelier &#8211; Annahid Dashtgard"}]},{"@type":"WebSite","@id":"https:\/\/www.hireimmigrantsottawa.ca\/#website","url":"https:\/\/www.hireimmigrantsottawa.ca\/","name":"Hire Immigrants Ottawa","description":"increases the capacity of employers to attract and integrate skilled immigrants","publisher":{"@id":"https:\/\/www.hireimmigrantsottawa.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hireimmigrantsottawa.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.hireimmigrantsottawa.ca\/#organization","name":"Hire Immigrants Ottawa","url":"https:\/\/www.hireimmigrantsottawa.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hireimmigrantsottawa.ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2023\/10\/hio-logo_bow_EN_web.png","contentUrl":"https:\/\/www.hireimmigrantsottawa.ca\/wp-content\/uploads\/2023\/10\/hio-logo_bow_EN_web.png","width":745,"height":160,"caption":"Hire Immigrants Ottawa"},"image":{"@id":"https:\/\/www.hireimmigrantsottawa.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/HireImmOttawa","https:\/\/www.youtube.com\/user\/hireimmigrantsottawa"]}]}},"_links":{"self":[{"href":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/wp-json\/wp\/v2\/2016-ecc-post\/3798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/wp-json\/wp\/v2\/2016-ecc-post"}],"about":[{"href":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/wp-json\/wp\/v2\/types\/2016-ecc-post"}],"version-history":[{"count":5,"href":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/wp-json\/wp\/v2\/2016-ecc-post\/3798\/revisions"}],"predecessor-version":[{"id":3859,"href":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/wp-json\/wp\/v2\/2016-ecc-post\/3798\/revisions\/3859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/wp-json\/wp\/v2\/media\/3797"}],"wp:attachment":[{"href":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/wp-json\/wp\/v2\/media?parent=3798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/wp-json\/wp\/v2\/categories?post=3798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hireimmigrantsottawa.ca\/fr\/wp-json\/wp\/v2\/tags?post=3798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}